{"id":41707,"date":"2024-06-11T15:47:54","date_gmt":"2024-06-11T15:47:54","guid":{"rendered":"https:\/\/alltestpro.com\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/"},"modified":"2024-06-11T18:45:13","modified_gmt":"2024-06-11T18:45:13","slug":"seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre","status":"publish","type":"av-events","link":"https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/","title":{"rendered":"S\u00e9minaire en ligne sur le diagnostic automobile de classe mondiale &#8211; Niveau 1 &#8211; 23-27 septembre"},"content":{"rendered":"<p>Avez-vous entendu ? Nous organiserons notre <strong>s\u00e9minaire World Class Motor Diagnostic Seminar Level 1 du<\/strong> <strong>23 au 27 septembre<\/strong>.<\/p>\n<p>Il s&#8217;agit d&#8217;un <strong>s\u00e9minaire en ligne\/virtuel<\/strong> qui d\u00e9butera chaque jour \u00e0 <strong>8 heures CST\/9 heures EST.<\/strong><\/p>\n<p>Il s&#8217;agit d&#8217;une excellente occasion pour les superviseurs et les techniciens d&#8217;apprendre et de d\u00e9velopper de nouvelles comp\u00e9tences afin d&#8217;am\u00e9liorer leurs comp\u00e9tences en mati\u00e8re de maintenance et de fiabilit\u00e9 !<\/p>\n<p>Vous pouvez vous inscrire et pr\u00e9payer pour le s\u00e9minaire en ligne via les liens ci-dessous ou en nous contactant.<\/p>\n<p><strong>Th\u00e8mes abord\u00e9s :<\/strong><\/p>\n<ul>\n<li>Histoire de l&#8217;\u00e9lectricit\u00e9 et des essais de moteurs<\/li>\n<li>Examen de la th\u00e9orie DC<\/li>\n<li>Examen de la th\u00e9orie de l&#8217;AC\n<ul>\n<li>Circuits CA Courant, Imp\u00e9dance, Puissance<\/li>\n<li>R\u00e9sistance, r\u00e9actance, imp\u00e9dance<\/li>\n<\/ul>\n<\/li>\n<li>Syst\u00e8mes de distribution \u00e9lectrique et de mise \u00e0 la terre<\/li>\n<li>Construction et fonctionnement des moteurs<\/li>\n<li>S\u00e9curit\u00e9 \u00e9lectrique\n<ul>\n<li>S\u00e9curit\u00e9 \u00e9lectrique et risques associ\u00e9s<\/li>\n<li>Normes et r\u00e9f\u00e9rences \u00e0 l&#8217;appui des essais de moteurs<\/li>\n<\/ul>\n<\/li>\n<li>Th\u00e9orie \u00e0 l&#8217;appui des essais de moteurs \u00e9lectriques hors tension<\/li>\n<li>Qualit\u00e9 de l&#8217;\u00e9nergie\n<ul>\n<li>Facteurs affectant la tension et le courant \u00e9quilibr\u00e9s<\/li>\n<li>\u00c9v\u00e9nements \u00e0 haute et basse fr\u00e9quence<\/li>\n<\/ul>\n<\/li>\n<li>Analyse de la signature du courant du moteur<\/li>\n<li>Analyse de la signature \u00e9lectrique<\/li>\n<li>Le\u00e7ons pratiques avec les instruments MCA et ESA<\/li>\n<li>Questions-r\u00e9ponses personnalis\u00e9es<\/li>\n<\/ul>\n<h5><strong>Conditions et d\u00e9tails du s\u00e9minaire<br \/>\n<\/strong><\/h5>\n<ul>\n<li>Les participants doivent poss\u00e9der un appareil MCA ou ESA (en fonction du cours).<\/li>\n<li>Les frais d&#8217;exp\u00e9dition du moteur et de la bobine jusqu&#8217;\u00e0 votre lieu de r\u00e9sidence seront indiqu\u00e9s au moment de la demande\/inscription au s\u00e9minaire.<\/li>\n<li>Le s\u00e9minaire se d\u00e9roulera uniquement en anglais<\/li>\n<li>Le s\u00e9minaire sera h\u00e9berg\u00e9 sur Microsoft Teams<\/li>\n<li>Les prix s&#8217;entendent par personne participant au s\u00e9minaire<\/li>\n<li>Jusqu&#8217;\u00e0 3 participants au s\u00e9minaire MCA d&#8217;un m\u00eame groupe\/local peuvent partager un instrument, une bobine d&#8217;essai et un moteur de d\u00e9faut. Veuillez contacter <a href=\"mailto:sales@alltestpro.com\">sales@alltestpro.com<\/a> pour obtenir un devis.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3><strong>Options de cours :<\/strong><\/h3>\n<p><strong><br \/>\nOption 1 :<br \/>\n<\/strong><br \/>\nMCA\u2122 (hors tension) et ESA (sous tension)<br \/>\nCours de 5 jours<\/p>\n<p><em>Info :<\/em><\/p>\n<p>Formation compl\u00e8te de 5 jours MCA\u2122 (De-Energized) + ESA (Energized). Trois jours de formation MCA\u2122 (De-Energized) vous pr\u00e9parent \u00e0 d\u00e9panner tous les types de moteurs \u00e9lectriques, de bobines et d&#8217;enroulements. Deux jours et demi de formation ESA (Energized) vous pr\u00e9parent \u00e0 \u00e9valuer de nombreux types de syst\u00e8mes de moteurs \u00e9lectriques afin d&#8217;am\u00e9liorer la fiabilit\u00e9 et le temps de fonctionnement de votre usine.<\/p>\n<p><em>Comprend :<\/em><\/p>\n<p>Un moteur de d\u00e9faut (part#40070) et une bobine de test<br \/>\nMat\u00e9riel de cours (manuel d&#8217;exercices, manuel d&#8217;analyse des circuits de moteur et reconnaissance des formes)<\/p>\n<p>&nbsp;<\/p>\n<hr>\n<p>&nbsp;<\/p>\n<p><strong>Option 2 :<br \/>\n<\/strong><br \/>\nMCA\u2122 (hors tension) uniquement<br \/>\nCours de 3 jours<\/p>\n<p><em>Info :<\/em><\/p>\n<p>Trois jours de formation MCA\u2122 (De-Energized) vous pr\u00e9parent \u00e0 d\u00e9panner tous les types de moteurs \u00e9lectriques, de bobines et d&#8217;enroulements.<\/p>\n<p><em>Comprend :<\/em><\/p>\n<p>Un moteur de d\u00e9faut (part#40070) et une bobine de test<br \/>\nMat\u00e9riel de cours (manuel d&#8217;exercices, manuel d&#8217;analyse des circuits de moteur et reconnaissance des formes)<\/p>\n<p>&nbsp;<\/p>\n<hr>\n<p>&nbsp;<\/p>\n<p><strong>Option 3 :<br \/>\n<\/strong><br \/>\nESA (Energized) uniquement<br \/>\nCours de 2,5 jours<\/p>\n<p><em>Info :<\/em><\/p>\n<p>Deux jours et demi de formation ESA (Energized) vous pr\u00e9parent \u00e0 \u00e9valuer de nombreux types de syst\u00e8mes de moteurs \u00e9lectriques afin d&#8217;am\u00e9liorer la fiabilit\u00e9 et le temps de fonctionnement de votre usine.<\/p>\n<p><em>Comprend :<\/em><\/p>\n<p>Un moteur de d\u00e9faut (part#40070) et une bobine de test<br \/>\nMat\u00e9riel de cours (cahier d&#8217;exercices et reconnaissance des formes)<\/p>\n<p>&nbsp;<\/p>\n<hr>\n<p>&nbsp;<\/p>\n<div id=\"product-component-1718126334933\"><\/div>\n<p><script type=\"text\/javascript\">\n\/*<![CDATA[*\/ (function () { var scriptURL = 'https:\/\/sdks.shopifycdn.com\/buy-button\/latest\/buy-button-storefront.min.js'; if (window.ShopifyBuy) { if (window.ShopifyBuy.UI) { ShopifyBuyInit(); } else { loadScript(); } } else { loadScript(); } function loadScript() { var script = document.createElement('script'); script.async = true; script.src = scriptURL; (document.getElementsByTagName('head')[0] || document.getElementsByTagName('body')[0]).appendChild(script); script.onload = ShopifyBuyInit; } function ShopifyBuyInit() { var client = ShopifyBuy.buildClient({ domain: 'alltestpro.myshopify.com', storefrontAccessToken: '518041dad93595901d8017463100993a', }); ShopifyBuy.UI.onReady(client).then(function (ui) { ui.createComponent('product', { id: '9479428800800', node: document.getElementById('product-component-1718126334933'), moneyFormat: '%24%7B%7Bamount%7D%7D', options: { \"product\": { \"styles\": { \"product\": { \"@media (min-width: 601px)\": { \"max-width\": \"calc(25% - 20px)\", \"margin-left\": \"20px\", \"margin-bottom\": \"50px\" } }, \"title\": { \"font-family\": \"Roboto, sans-serif\", \"font-weight\": \"normal\", \"font-size\": \"17px\" }, \"button\": { \"font-family\": \"Roboto, sans-serif\", \"font-size\": \"14px\", \"padding-top\": \"15px\", \"padding-bottom\": \"15px\", \":hover\": { \"background-color\": \"#b40e29\" }, \"background-color\": \"#c8102e\", \":focus\": { \"background-color\": \"#b40e29\" }, \"border-radius\": \"40px\", \"padding-left\": \"30px\", \"padding-right\": \"30px\" }, \"quantityInput\": { \"font-size\": \"14px\", \"padding-top\": \"15px\", \"padding-bottom\": \"15px\" }, \"price\": { \"font-family\": \"Roboto, sans-serif\" }, \"compareAt\": { \"font-family\": \"Roboto, sans-serif\" }, \"unitPrice\": { \"font-family\": \"Roboto, sans-serif\" } }, \"text\": { \"button\": \"REGISTER\" }, \"googleFonts\": [ \"Roboto\" ] }, \"productSet\": { \"styles\": { \"products\": { \"@media (min-width: 601px)\": { \"margin-left\": \"-20px\" } } } }, \"modalProduct\": { \"contents\": { \"img\": false, \"imgWithCarousel\": true, \"button\": false, \"buttonWithQuantity\": true }, \"styles\": { \"product\": { \"@media (min-width: 601px)\": { \"max-width\": \"100%\", \"margin-left\": \"0px\", \"margin-bottom\": \"0px\" } }, \"button\": { \"font-family\": \"Roboto, sans-serif\", \"font-size\": \"14px\", \"padding-top\": \"15px\", \"padding-bottom\": \"15px\", \":hover\": { \"background-color\": \"#b40e29\" }, \"background-color\": \"#c8102e\", \":focus\": { \"background-color\": \"#b40e29\" }, \"border-radius\": \"40px\", \"padding-left\": \"30px\", \"padding-right\": \"30px\" }, \"quantityInput\": { \"font-size\": \"14px\", \"padding-top\": \"15px\", \"padding-bottom\": \"15px\" }, \"title\": { \"font-family\": \"Helvetica Neue, sans-serif\", \"font-weight\": \"bold\", \"font-size\": \"26px\", \"color\": \"#4c4c4c\" }, \"price\": { \"font-family\": \"Helvetica Neue, sans-serif\", \"font-weight\": \"normal\", \"font-size\": \"18px\", \"color\": \"#4c4c4c\" }, \"compareAt\": { \"font-family\": \"Helvetica Neue, sans-serif\", \"font-weight\": \"normal\", \"font-size\": \"15.299999999999999px\", \"color\": \"#4c4c4c\" }, \"unitPrice\": { \"font-family\": \"Helvetica Neue, sans-serif\", \"font-weight\": \"normal\", \"font-size\": \"15.299999999999999px\", \"color\": \"#4c4c4c\" } }, \"googleFonts\": [ \"Roboto\" ], \"text\": { \"button\": \"Add to cart\" } }, \"option\": { \"styles\": { \"label\": { \"font-family\": \"Roboto, sans-serif\" }, \"select\": { \"font-family\": \"Roboto, sans-serif\" } }, \"googleFonts\": [ \"Roboto\" ] }, \"cart\": { \"styles\": { \"button\": { \"font-family\": \"Roboto, sans-serif\", \"font-size\": \"14px\", \"padding-top\": \"15px\", \"padding-bottom\": \"15px\", \":hover\": { \"background-color\": \"#b40e29\" }, \"background-color\": \"#c8102e\", \":focus\": { \"background-color\": \"#b40e29\" }, \"border-radius\": \"40px\" } }, \"text\": { \"total\": \"Subtotal\", \"notice\": \"Shipping and taxes are added at checkout. Duties\/fees on international orders are not collected at the time of purchase.\", \"button\": \"Checkout\" }, \"popup\": false, \"googleFonts\": [ \"Roboto\" ] }, \"toggle\": { \"styles\": { \"toggle\": { \"font-family\": \"Roboto, sans-serif\", \"background-color\": \"#c8102e\", \":hover\": { \"background-color\": \"#b40e29\" }, \":focus\": { \"background-color\": \"#b40e29\" } }, \"count\": { \"font-size\": \"14px\" } }, \"googleFonts\": [ \"Roboto\" ] } }, }); }); } })(); \/*]]>*\/\n<\/script><\/p>\n<p>&nbsp;<\/p>\n<p>Si vous avez des questions, veuillez nous contacter \u00e0 l&#8217;adresse <a href=\"mailto:sales@alltestpro.com\">suivante : sales@alltestpro.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avez-vous entendu ? Nous organiserons notre s\u00e9minaire World Class Motor Diagnostic Seminar Level 1 du 23 au 27 septembre. Il s&#8217;agit d&#8217;un s\u00e9minaire en ligne\/virtuel qui d\u00e9butera chaque jour \u00e0 [&hellip;]<\/p>\n","protected":false},"featured_media":41629,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"event_category":[368],"class_list":["post-41707","av-events","type-av-events","status-publish","has-post-thumbnail","hentry","event_category-online-public"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e9minaire en ligne sur le diagnostic automobile de classe mondiale - Niveau 1 - 23-27 septembre - Electric Motor Testing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9minaire en ligne sur le diagnostic automobile de classe mondiale - Niveau 1 - 23-27 septembre - Electric Motor Testing\" \/>\n<meta property=\"og:description\" content=\"Avez-vous entendu ? Nous organiserons notre s\u00e9minaire World Class Motor Diagnostic Seminar Level 1 du 23 au 27 septembre. Il s&#8217;agit d&#8217;un s\u00e9minaire en ligne\/virtuel qui d\u00e9butera chaque jour \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Electric Motor Testing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/electric.motor.testing.equipment\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T18:45:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alltestpro.com\/wp-content\/uploads\/2024\/06\/New-Project-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alltestpro.com\\\/fr\\\/events\\\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\\\/\",\"url\":\"https:\\\/\\\/alltestpro.com\\\/fr\\\/events\\\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\\\/\",\"name\":\"S\u00e9minaire en ligne sur le diagnostic automobile de classe mondiale - Niveau 1 - 23-27 septembre - Electric Motor Testing\",\"isPartOf\":{\"@id\":\"\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alltestpro.com\\\/fr\\\/events\\\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alltestpro.com\\\/fr\\\/events\\\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alltestpro.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/New-Project-12.jpg\",\"datePublished\":\"2024-06-11T15:47:54+00:00\",\"dateModified\":\"2024-06-11T18:45:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alltestpro.com\\\/fr\\\/events\\\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alltestpro.com\\\/fr\\\/events\\\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alltestpro.com\\\/fr\\\/events\\\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alltestpro.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/New-Project-12.jpg\",\"contentUrl\":\"https:\\\/\\\/alltestpro.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/New-Project-12.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alltestpro.com\\\/fr\\\/events\\\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alltestpro.com\\\/fr\\\/accueil-1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e9minaire en ligne sur le diagnostic automobile de classe mondiale &#8211; Niveau 1 &#8211; 23-27 septembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"\\\/#website\",\"url\":\"\\\/\",\"name\":\"Electric Motor Testing\",\"description\":\"\",\"publisher\":{\"@id\":\"\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"\\\/#organization\",\"name\":\"ALL-TEST Pro\",\"alternateName\":\"ATP\",\"url\":\"\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alltestpro.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IATP_Logo_-2-_-_Copy-1-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/alltestpro.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IATP_Logo_-2-_-_Copy-1-1-1.jpg\",\"width\":700,\"height\":741,\"caption\":\"ALL-TEST Pro\"},\"image\":{\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/electric.motor.testing.equipment\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/all-test-pro-llc\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/alltestpro\",\"https:\\\/\\\/www.instagram.com\\\/alltestpro\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e9minaire en ligne sur le diagnostic automobile de classe mondiale - Niveau 1 - 23-27 septembre - Electric Motor Testing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/","og_locale":"fr_FR","og_type":"article","og_title":"S\u00e9minaire en ligne sur le diagnostic automobile de classe mondiale - Niveau 1 - 23-27 septembre - Electric Motor Testing","og_description":"Avez-vous entendu ? Nous organiserons notre s\u00e9minaire World Class Motor Diagnostic Seminar Level 1 du 23 au 27 septembre. Il s&#8217;agit d&#8217;un s\u00e9minaire en ligne\/virtuel qui d\u00e9butera chaque jour \u00e0 [&hellip;]","og_url":"https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/","og_site_name":"Electric Motor Testing","article_publisher":"https:\/\/www.facebook.com\/electric.motor.testing.equipment","article_modified_time":"2024-06-11T18:45:13+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/alltestpro.com\/wp-content\/uploads\/2024\/06\/New-Project-12.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/","url":"https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/","name":"S\u00e9minaire en ligne sur le diagnostic automobile de classe mondiale - Niveau 1 - 23-27 septembre - Electric Motor Testing","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/#primaryimage"},"image":{"@id":"https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/#primaryimage"},"thumbnailUrl":"https:\/\/alltestpro.com\/wp-content\/uploads\/2024\/06\/New-Project-12.jpg","datePublished":"2024-06-11T15:47:54+00:00","dateModified":"2024-06-11T18:45:13+00:00","breadcrumb":{"@id":"https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/#primaryimage","url":"https:\/\/alltestpro.com\/wp-content\/uploads\/2024\/06\/New-Project-12.jpg","contentUrl":"https:\/\/alltestpro.com\/wp-content\/uploads\/2024\/06\/New-Project-12.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/alltestpro.com\/fr\/events\/seminaire-en-ligne-sur-le-diagnostic-automobile-de-classe-mondiale-niveau-1-23-27-septembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alltestpro.com\/fr\/accueil-1\/"},{"@type":"ListItem","position":2,"name":"S\u00e9minaire en ligne sur le diagnostic automobile de classe mondiale &#8211; Niveau 1 &#8211; 23-27 septembre"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Electric Motor Testing","description":"","publisher":{"@id":"\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"\/#organization","name":"ALL-TEST Pro","alternateName":"ATP","url":"\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"\/#\/schema\/logo\/image\/","url":"https:\/\/alltestpro.com\/wp-content\/uploads\/2023\/04\/IATP_Logo_-2-_-_Copy-1-1-1.jpg","contentUrl":"https:\/\/alltestpro.com\/wp-content\/uploads\/2023\/04\/IATP_Logo_-2-_-_Copy-1-1-1.jpg","width":700,"height":741,"caption":"ALL-TEST Pro"},"image":{"@id":"\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/electric.motor.testing.equipment","https:\/\/www.linkedin.com\/company\/all-test-pro-llc\/","https:\/\/www.youtube.com\/c\/alltestpro","https:\/\/www.instagram.com\/alltestpro\/"]}]}},"_links":{"self":[{"href":"https:\/\/alltestpro.com\/fr\/wp-json\/wp\/v2\/av-events\/41707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alltestpro.com\/fr\/wp-json\/wp\/v2\/av-events"}],"about":[{"href":"https:\/\/alltestpro.com\/fr\/wp-json\/wp\/v2\/types\/av-events"}],"replies":[{"embeddable":true,"href":"https:\/\/alltestpro.com\/fr\/wp-json\/wp\/v2\/comments?post=41707"}],"version-history":[{"count":1,"href":"https:\/\/alltestpro.com\/fr\/wp-json\/wp\/v2\/av-events\/41707\/revisions"}],"predecessor-version":[{"id":41717,"href":"https:\/\/alltestpro.com\/fr\/wp-json\/wp\/v2\/av-events\/41707\/revisions\/41717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alltestpro.com\/fr\/wp-json\/wp\/v2\/media\/41629"}],"wp:attachment":[{"href":"https:\/\/alltestpro.com\/fr\/wp-json\/wp\/v2\/media?parent=41707"}],"wp:term":[{"taxonomy":"event_category","embeddable":true,"href":"https:\/\/alltestpro.com\/fr\/wp-json\/wp\/v2\/event_category?post=41707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}